{"id":281,"date":"2024-05-07T14:13:48","date_gmt":"2024-05-07T08:43:48","guid":{"rendered":"http:\/\/10.10.0.172\/sbsweb\/?page_id=281"},"modified":"2025-04-09T12:11:03","modified_gmt":"2025-04-09T06:41:03","slug":"programs","status":"publish","type":"page","link":"https:\/\/sbs.iitbbs.ac.in\/index.php\/physics\/programs\/","title":{"rendered":"Physics Programs"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"281\" class=\"elementor elementor-281\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-220e4d4 e-flex e-con-boxed e-con e-parent\" data-id=\"220e4d4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c91676d elementor-widget elementor-widget-heading\" data-id=\"c91676d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Programs<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52e23f5 e-flex e-con-boxed e-con e-parent\" data-id=\"52e23f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48ece3b elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"48ece3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>The School offers a range of undergraduate, postgraduate, and doctoral programs designed to produce highly skilled professionals and researchers. Our programs are structured to provide a solid foundation in theoretical principles, complemented by practical exposure and research opportunities. The curriculum consists of interdisciplinary courses, emphasizes seminars, projects, and internships to prepare students to take up challenges in academia, industry, and research.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70ebf06 e-flex e-con-boxed e-con e-parent\" data-id=\"70ebf06\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2c288ac e-con-full e-flex e-con e-child\" data-id=\"2c288ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-26944a4 e-con-full e-flex e-con e-child\" data-id=\"26944a4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-06f7228 elementor-widget elementor-widget-heading\" data-id=\"06f7228\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">UG Programs<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-692820b elementor-widget elementor-widget-text-editor\" data-id=\"692820b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><b>BTech in <\/b><a href=\"https:\/\/www.iitbbs.ac.in\/wp-content\/uploads\/2024\/05\/Engineering-Physics_Curriculum_Details_15.05_ERP2.pdf\">Engineering Physics<\/a><\/li><li><b>BSc-BEd (ITEP)<\/b> in <a href=\"https:\/\/www.iitbbs.ac.in\/index.php\/home\/academics\/b-sc-b-ed-physics\/\">Physics<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f04c80d e-con-full e-flex e-con e-child\" data-id=\"f04c80d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dc7b695 e-con-full e-flex e-con e-child\" data-id=\"dc7b695\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-95e448d elementor-widget elementor-widget-heading\" data-id=\"95e448d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">PG Programs<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4791b55 elementor-widget elementor-widget-text-editor\" data-id=\"4791b55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><b>Joint MSc-PhD <\/b>in <a href=\"https:\/\/www.iitbbs.ac.in\/index.php\/home\/academics\/curriculum-m-sc\/curriculum-for-m-sc-physics\/\">Physics<\/a><\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-025f8e2 e-flex e-con-boxed e-con e-parent\" data-id=\"025f8e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e8e1a5e e-con-full e-flex e-con e-child\" data-id=\"e8e1a5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-09a3e78 e-con-full e-flex e-con e-child\" data-id=\"09a3e78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1480ddc elementor-widget elementor-widget-heading\" data-id=\"1480ddc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Doctoral Program<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2ad0e0 elementor-widget elementor-widget-text-editor\" data-id=\"c2ad0e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p><b>PhD\u00a0<\/b> in Physics<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96aeff0 e-con-full e-flex e-con e-child\" data-id=\"96aeff0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a208c26 e-con-full e-flex e-con e-child\" data-id=\"a208c26\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b199853 elementor-widget elementor-widget-heading\" data-id=\"b199853\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Other Programs<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89583c5 elementor-widget elementor-widget-text-editor\" data-id=\"89583c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><a href=\"https:\/\/www.iitbbs.ac.in\/index.php\/home\/academics\/internship-programme\/\">Summer and Winter Internships<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Programs The School offers a range of undergraduate, postgraduate, and doctoral programs designed to produce highly skilled professionals and researchers. [&hellip;]<\/p>\n","protected":false},"author":51,"featured_media":0,"parent":3590,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-281","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/pages\/281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":93,"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/pages\/281\/revisions"}],"predecessor-version":[{"id":7421,"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/pages\/281\/revisions\/7421"}],"up":[{"embeddable":true,"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/pages\/3590"}],"wp:attachment":[{"href":"https:\/\/sbs.iitbbs.ac.in\/index.php\/wp-json\/wp\/v2\/media?parent=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}